{"id":1813,"date":"2017-03-01T15:36:55","date_gmt":"2017-03-01T14:36:55","guid":{"rendered":"http:\/\/eichinger.de.w0094cee.kasserver.com\/kontakt\/"},"modified":"2026-06-07T09:49:36","modified_gmt":"2026-06-07T07:49:36","slug":"contact","status":"publish","type":"page","link":"https:\/\/eichinger.de\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7275&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;20&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7254&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;120&#8243; custom_sizes_attr=&#8221;px&#8221;][vc_column_text]\n<h2>Contact<\/h2>\n<p>Please call us during our office hours:<\/p>\n<p>Monday &#8211; Thursday:\u00a0 7:30 am &#8211; 5:00 pm<br \/>\nFriday:\u00a0 7:30 am &#8211; 2:30 pm<\/p>\n<h3>+49 9185 923-0<\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7270&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;120&#8243; custom_sizes_attr=&#8221;px&#8221;][vc_column_text]\n<h2>Service<\/h2>\n<p>Please call us during our office hours:<\/p>\n<p>Monday &#8211; Thursday:\u00a0 7:30 am &#8211; 5:00 pm<br \/>\nFriday:\u00a0 7:30 am &#8211; 2:30 pm<\/p>\n<h3>+49 9185 923-0<\/h3>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;7265&#8243; image_size=&#8221;full&#8221; max_width=&#8221;custom&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width_custom=&#8221;120&#8243; custom_sizes_attr=&#8221;px&#8221;][vc_column_text]\n<h2>Delivery \/ Pick up<\/h2>\n<p>Please call us during our office hours:<\/p>\n<p>Monday &#8211; Thursday:\u00a0 7:30 am &#8211; 5:00 pm<br \/>\nFriday:\u00a0 7:30 am &#8211; 2:30 pm<\/p>\n<h3>+49 9185 923-0<\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; boxed=&#8221;true&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][nectar_cta btn_style=&#8221;see-through&#8221; heading_tag=&#8221;h2&#8243; link_type=&#8221;regular&#8221; button_color=&#8221;default&#8221; button_border_thickness=&#8221;0px&#8221; alignment=&#8221;left&#8221; alignment_tablet=&#8221;default&#8221; alignment_phone=&#8221;default&#8221; display=&#8221;block&#8221; display_tablet=&#8221;inherit&#8221; display_phone=&#8221;inherit&#8221; text=&#8221;&#8230; or contact us by email:&#8221; link_text=&#8221;info@eichinger.de&#8221; url=&#8221;mailto:info@eichinger.de&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; row_position_desktop=&#8221;default&#8221; row_position_tablet=&#8221;inherit&#8221; row_position_phone=&#8221;inherit&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; flex_gap_desktop=&#8221;10px&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1813","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Contact | Eichinger Equipment<\/title>\n<meta name=\"description\" content=\"Your contact at Florian Eichinger GmbH \u2013 construction equipment, management, service, accessories, your national and international contacts\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eichinger.de\/en\/contact\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contact | Eichinger Equipment\" \/>\n<meta property=\"og:description\" content=\"Your contact at Florian Eichinger GmbH \u2013 construction equipment, management, service, accessories, your national and international contacts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eichinger.de\/en\/contact\/\" \/>\n<meta property=\"og:site_name\" content=\"florianeichinger.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100076148208209\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-07T07:49:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/contact\\\/\",\"url\":\"https:\\\/\\\/eichinger.de\\\/en\\\/contact\\\/\",\"name\":\"Contact | Eichinger Equipment\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/#website\"},\"datePublished\":\"2017-03-01T14:36:55+00:00\",\"dateModified\":\"2026-06-07T07:49:36+00:00\",\"description\":\"Your contact at Florian Eichinger GmbH \u2013 construction equipment, management, service, accessories, your national and international contacts\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/contact\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eichinger.de\\\/en\\\/contact\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/contact\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/eichinger.de\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contact\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/eichinger.de\\\/en\\\/\",\"name\":\"eichinger.de\",\"description\":\"FE Eichinger Equipment\",\"publisher\":{\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/#organization\"},\"alternateName\":\"Florian Eichinger GmbH - Kranzubeh\u00f6r und Hebezeuge f\u00fcr BAU\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eichinger.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/#organization\",\"name\":\"Florian Eichinger GmbH\",\"alternateName\":\"Eichinger Equipment\",\"url\":\"https:\\\/\\\/eichinger.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/eichinger.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Eichinger_blanko_orange_696x696px.webp\",\"contentUrl\":\"https:\\\/\\\/eichinger.de\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Eichinger_blanko_orange_696x696px.webp\",\"width\":696,\"height\":696,\"caption\":\"Florian Eichinger GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/eichinger.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100076148208209\",\"https:\\\/\\\/www.instagram.com\\\/florianeichingergmbh\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/florian-eichinger-gmbh\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contact | Eichinger Equipment","description":"Your contact at Florian Eichinger GmbH \u2013 construction equipment, management, service, accessories, your national and international contacts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eichinger.de\/en\/contact\/","og_locale":"en_US","og_type":"article","og_title":"Contact | Eichinger Equipment","og_description":"Your contact at Florian Eichinger GmbH \u2013 construction equipment, management, service, accessories, your national and international contacts","og_url":"https:\/\/eichinger.de\/en\/contact\/","og_site_name":"florianeichinger.com","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100076148208209","article_modified_time":"2026-06-07T07:49:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eichinger.de\/en\/contact\/","url":"https:\/\/eichinger.de\/en\/contact\/","name":"Contact | Eichinger Equipment","isPartOf":{"@id":"https:\/\/eichinger.de\/en\/#website"},"datePublished":"2017-03-01T14:36:55+00:00","dateModified":"2026-06-07T07:49:36+00:00","description":"Your contact at Florian Eichinger GmbH \u2013 construction equipment, management, service, accessories, your national and international contacts","breadcrumb":{"@id":"https:\/\/eichinger.de\/en\/contact\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eichinger.de\/en\/contact\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/eichinger.de\/en\/contact\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/eichinger.de\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Contact"}]},{"@type":"WebSite","@id":"https:\/\/eichinger.de\/en\/#website","url":"https:\/\/eichinger.de\/en\/","name":"eichinger.de","description":"FE Eichinger Equipment","publisher":{"@id":"https:\/\/eichinger.de\/en\/#organization"},"alternateName":"Florian Eichinger GmbH - Kranzubeh\u00f6r und Hebezeuge f\u00fcr BAU","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eichinger.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/eichinger.de\/en\/#organization","name":"Florian Eichinger GmbH","alternateName":"Eichinger Equipment","url":"https:\/\/eichinger.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eichinger.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/eichinger.de\/wp-content\/uploads\/2026\/05\/Eichinger_blanko_orange_696x696px.webp","contentUrl":"https:\/\/eichinger.de\/wp-content\/uploads\/2026\/05\/Eichinger_blanko_orange_696x696px.webp","width":696,"height":696,"caption":"Florian Eichinger GmbH"},"image":{"@id":"https:\/\/eichinger.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100076148208209","https:\/\/www.instagram.com\/florianeichingergmbh\/","https:\/\/www.linkedin.com\/company\/florian-eichinger-gmbh\/"]}]}},"_links":{"self":[{"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/pages\/1813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/comments?post=1813"}],"version-history":[{"count":2,"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/pages\/1813\/revisions"}],"predecessor-version":[{"id":7888,"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/pages\/1813\/revisions\/7888"}],"wp:attachment":[{"href":"https:\/\/eichinger.de\/en\/wp-json\/wp\/v2\/media?parent=1813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}